{"id":9566,"date":"2024-01-30T09:33:19","date_gmt":"2024-01-30T15:33:19","guid":{"rendered":"https:\/\/sunsetmonalisa.com\/?p=9566"},"modified":"2024-11-30T15:02:40","modified_gmt":"2024-11-30T21:02:40","slug":"los250mx","status":"publish","type":"post","link":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/","title":{"rendered":"Celebrando la Excelencia Culinaria"},"content":{"rendered":"<h1>Celebrando la Excelencia Culinaria: Congreso Gastron\u00f3mico Mexicano 2024<\/h1>\n<p>&nbsp;<\/p>\n<p>M\u00e9xico es un pa\u00eds identificado por su vibrante cultura y su rico patrimonio culinario. Los restaurantes en Los Cabos son una muestra del compromiso con la gastronom\u00eda.<\/p>\n<p>\u201c<strong>Oficios Culinarios<\/strong>\u201d re\u00fane a los actores destacados en esta industria mexicana. El evento anual premia a los chefs y restaurantes m\u00e1s sobresalientes. En el marco de la gran reuni\u00f3n nacional,\u00a0<strong>Grupo Culinaria Mexicana<\/strong>\u00a0hace entrega 250 preseas que reconocen proyectos responsables que proveen alimentos sin da\u00f1ar el medioambiente y beneficien a la sociedad.<\/p>\n<p>Para seleccionar la lista de los\u00a0<strong>250 restaurantes<\/strong>\u00a0que integrar\u00e1n la publicaci\u00f3n emblem\u00e1tica\u00a0<strong>Larousse de Cocina<\/strong>, se forma un Consejo Editorial de Votantes integrado por 60 personajes de la industria culinaria, entre los que se encuentran editores de grandes publicaciones, fot\u00f3grafos de alimentos, empresarios y periodistas.<\/p>\n<p>&nbsp;<\/p>\n<div id='gallery-1' class='gallery galleryid-9566 gallery-columns-3 gallery-size-large'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/Los250Mx_SunsetMonalisa_1-600x600-1.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/Los250Mx_SunsetMonalisa_1-600x600-1.webp 600w, https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/Los250Mx_SunsetMonalisa_1-600x600-1-300x300.webp 300w, https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/Los250Mx_SunsetMonalisa_1-600x600-1-150x150.webp 150w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/Los250Mx_SunsetMonalisa_2-600x600-1.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/Los250Mx_SunsetMonalisa_2-600x600-1.webp 600w, https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/Los250Mx_SunsetMonalisa_2-600x600-1-300x300.webp 300w, https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/Los250Mx_SunsetMonalisa_2-600x600-1-150x150.webp 150w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/Los250Mx_SunsetMonalisa_3-600x600-1.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/Los250Mx_SunsetMonalisa_3-600x600-1.webp 600w, https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/Los250Mx_SunsetMonalisa_3-600x600-1-300x300.webp 300w, https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/Los250Mx_SunsetMonalisa_3-600x600-1-150x150.webp 150w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>&nbsp;<\/p>\n<p>Dentro de este contexto,\u00a0<strong>Sunset Monalisa<\/strong>\u00a0es uno de los nuevos integrantes @los250mx 2024. H\u00e9ctor Morales, Chef Ejecutivo y Giuseppe Napoli, Director General de Grupo Monalisa participaron en esta noche tan especial para la gastronom\u00eda mexicana. La celebraci\u00f3n de los 10 a\u00f1os se llev\u00f3 a cabo en la Universidad del Claustro de Sor Juana bajo la organizaci\u00f3n de @sanpellegrino_mx y @nespresso.mx. Es una gu\u00eda publicada por @laroussecocinamx y presentada por @audidemexico.<\/p>\n<p>Los premios de\u00a0<strong>Gu\u00eda M\u00e9xico Gastron\u00f3mico Culinaria Mexicana<\/strong>\u00a0es una plataforma para honrar la pasi\u00f3n inquebrantable, la notable creatividad y la dedicaci\u00f3n incansable de quienes contribuyen a la evoluci\u00f3n constante de la cocina mexicana.<\/p>\n<p>Mientras celebramos a los restaurantes que conforman la publicaci\u00f3n anual 2024, no solo se reconocen sus logros en el mundo culinario, sino que tambi\u00e9n inspiran una nueva generaci\u00f3n de chefs y entusiastas de la comida a traspasar los l\u00edmites y explorar las infinitas posibilidades de los sabores e ingredientes.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Celebrando la Excelencia Culinaria: Congreso Gastron\u00f3mico Mexicano 2024 &nbsp; M\u00e9xico es un pa\u00eds identificado por su vibrante cultura y su [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[31],"tags":[],"class_list":["post-9566","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Celebrando la Excelencia Culinaria | Sunset Monalisa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sunsetmonalisa.com\/es\/los250mx\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Celebrando la Excelencia Culinaria\" \/>\n<meta property=\"og:description\" content=\"Celebrando la Excelencia Culinaria: Congreso Gastron\u00f3mico Mexicano 2024 &nbsp; M\u00e9xico es un pa\u00eds identificado por su vibrante cultura y su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sunsetmonalisa.com\/es\/los250mx\/\" \/>\n<meta property=\"og:site_name\" content=\"Sunset Monalisa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SunsetMonalisa\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-30T15:33:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-30T21:02:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/TopRestaurant_SunsetMonalisa_250.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1001\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"TheSimpleContext\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"TheSimpleContext\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/los250mx\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/los250mx\\\/\"},\"author\":{\"name\":\"TheSimpleContext\",\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/#\\\/schema\\\/person\\\/fd847db2739e465d38055127b142ab46\"},\"headline\":\"Celebrando la Excelencia Culinaria\",\"datePublished\":\"2024-01-30T15:33:19+00:00\",\"dateModified\":\"2024-11-30T21:02:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/los250mx\\\/\"},\"wordCount\":327,\"publisher\":{\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/los250mx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sunsetmonalisa.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/TopRestaurant_SunsetMonalisa_250.webp\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/los250mx\\\/\",\"url\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/los250mx\\\/\",\"name\":\"Celebrando la Excelencia Culinaria | Sunset Monalisa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/los250mx\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/los250mx\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sunsetmonalisa.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/TopRestaurant_SunsetMonalisa_250.webp\",\"datePublished\":\"2024-01-30T15:33:19+00:00\",\"dateModified\":\"2024-11-30T21:02:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/los250mx\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/los250mx\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/los250mx\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sunsetmonalisa.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/TopRestaurant_SunsetMonalisa_250.webp\",\"contentUrl\":\"https:\\\/\\\/sunsetmonalisa.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/TopRestaurant_SunsetMonalisa_250.webp\",\"width\":1001,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/los250mx\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Celebrando la Excelencia Culinaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/\",\"name\":\"Sunset Monalisa\",\"description\":\"A culinary delight\",\"publisher\":{\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/#organization\",\"name\":\"Sunset Monalisa\",\"url\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sunsetmonalisa.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Sunset-Monalisa-favicon-2_1.png\",\"contentUrl\":\"https:\\\/\\\/sunsetmonalisa.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Sunset-Monalisa-favicon-2_1.png\",\"width\":512,\"height\":512,\"caption\":\"Sunset Monalisa\"},\"image\":{\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SunsetMonalisa\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sunsetmonalisa\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@sunset.monalisa\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/#\\\/schema\\\/person\\\/fd847db2739e465d38055127b142ab46\",\"name\":\"TheSimpleContext\",\"url\":\"https:\\\/\\\/sunsetmonalisa.com\\\/es\\\/author\\\/thesimplecontext\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Celebrando la Excelencia Culinaria | Sunset Monalisa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/","og_locale":"es_ES","og_type":"article","og_title":"Celebrando la Excelencia Culinaria","og_description":"Celebrando la Excelencia Culinaria: Congreso Gastron\u00f3mico Mexicano 2024 &nbsp; M\u00e9xico es un pa\u00eds identificado por su vibrante cultura y su [&hellip;]","og_url":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/","og_site_name":"Sunset Monalisa","article_publisher":"https:\/\/www.facebook.com\/SunsetMonalisa\/","article_published_time":"2024-01-30T15:33:19+00:00","article_modified_time":"2024-11-30T21:02:40+00:00","og_image":[{"width":1001,"height":607,"url":"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/TopRestaurant_SunsetMonalisa_250.webp","type":"image\/webp"}],"author":"TheSimpleContext","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"TheSimpleContext","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/#article","isPartOf":{"@id":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/"},"author":{"name":"TheSimpleContext","@id":"https:\/\/sunsetmonalisa.com\/es\/#\/schema\/person\/fd847db2739e465d38055127b142ab46"},"headline":"Celebrando la Excelencia Culinaria","datePublished":"2024-01-30T15:33:19+00:00","dateModified":"2024-11-30T21:02:40+00:00","mainEntityOfPage":{"@id":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/"},"wordCount":327,"publisher":{"@id":"https:\/\/sunsetmonalisa.com\/es\/#organization"},"image":{"@id":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/#primaryimage"},"thumbnailUrl":"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/TopRestaurant_SunsetMonalisa_250.webp","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/","url":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/","name":"Celebrando la Excelencia Culinaria | Sunset Monalisa","isPartOf":{"@id":"https:\/\/sunsetmonalisa.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/#primaryimage"},"image":{"@id":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/#primaryimage"},"thumbnailUrl":"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/TopRestaurant_SunsetMonalisa_250.webp","datePublished":"2024-01-30T15:33:19+00:00","dateModified":"2024-11-30T21:02:40+00:00","breadcrumb":{"@id":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sunsetmonalisa.com\/es\/los250mx\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/#primaryimage","url":"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/TopRestaurant_SunsetMonalisa_250.webp","contentUrl":"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/11\/TopRestaurant_SunsetMonalisa_250.webp","width":1001,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/sunsetmonalisa.com\/es\/los250mx\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/sunsetmonalisa.com\/es\/"},{"@type":"ListItem","position":2,"name":"Celebrando la Excelencia Culinaria"}]},{"@type":"WebSite","@id":"https:\/\/sunsetmonalisa.com\/es\/#website","url":"https:\/\/sunsetmonalisa.com\/es\/","name":"Sunset Monalisa","description":"A culinary delight","publisher":{"@id":"https:\/\/sunsetmonalisa.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sunsetmonalisa.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/sunsetmonalisa.com\/es\/#organization","name":"Sunset Monalisa","url":"https:\/\/sunsetmonalisa.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/sunsetmonalisa.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/07\/Sunset-Monalisa-favicon-2_1.png","contentUrl":"https:\/\/sunsetmonalisa.com\/wp-content\/uploads\/2024\/07\/Sunset-Monalisa-favicon-2_1.png","width":512,"height":512,"caption":"Sunset Monalisa"},"image":{"@id":"https:\/\/sunsetmonalisa.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SunsetMonalisa\/","https:\/\/www.instagram.com\/sunsetmonalisa\/","https:\/\/www.tiktok.com\/@sunset.monalisa"]},{"@type":"Person","@id":"https:\/\/sunsetmonalisa.com\/es\/#\/schema\/person\/fd847db2739e465d38055127b142ab46","name":"TheSimpleContext","url":"https:\/\/sunsetmonalisa.com\/es\/author\/thesimplecontext\/"}]}},"_links":{"self":[{"href":"https:\/\/sunsetmonalisa.com\/es\/wp-json\/wp\/v2\/posts\/9566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sunsetmonalisa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sunsetmonalisa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sunsetmonalisa.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sunsetmonalisa.com\/es\/wp-json\/wp\/v2\/comments?post=9566"}],"version-history":[{"count":0,"href":"https:\/\/sunsetmonalisa.com\/es\/wp-json\/wp\/v2\/posts\/9566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sunsetmonalisa.com\/es\/wp-json\/wp\/v2\/media\/9400"}],"wp:attachment":[{"href":"https:\/\/sunsetmonalisa.com\/es\/wp-json\/wp\/v2\/media?parent=9566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sunsetmonalisa.com\/es\/wp-json\/wp\/v2\/categories?post=9566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sunsetmonalisa.com\/es\/wp-json\/wp\/v2\/tags?post=9566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}